{"id":18555,"date":"2024-04-22T12:30:00","date_gmt":"2024-04-22T04:30:00","guid":{"rendered":"https:\/\/www.franchise.com.hk\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555"},"modified":"2024-04-22T12:30:00","modified_gmt":"2024-04-22T04:30:00","slug":"%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99","status":"publish","type":"post","link":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555","title":{"rendered":"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9"},"content":{"rendered":"<p>\u9999\u6e2f2024\u5e744\u670822\u65e5 \/\u7f8e\u901a\u793e\/ &#8212; \u7345\u5b50\u96c6\u5718\u63a7\u80a1\u6709\u9650\u516c\u53f8(Lion Group Holding Ltd.)(&#8220;\u7345\u5b50\u96c6\u5718&#8221;\u6216&#8221;\u8a72\u96c6\u5718&#8221;)(\u7d0d\u65af\u9054\u514b\u80a1\u7968\u4ee3\u78bc\uff1aLGHL)\uff0c\u662f\u4e00\u5bb6\u70ba\u6295\u8cc7\u8005\u63d0\u4f9b\u5ee3\u6cdb\u7522\u54c1\u548c\u670d\u52d9\u7684\u4e00\u7ad9\u5f0f\u4ea4\u6613\u5e73\u53f0\u904b\u71df\u5546\uff0c\u4ee5\u53ca\u5c08\u6ce8\u65bc\u91d1\u878d\u79d1\u6280\u9818\u57df\u7684\u5275\u65b0\u7522\u54c1\u958b\u767c\u8005\u3002\u8a72\u96c6\u5718\u4eca\u65e5\u5ba3\u5e03\u91c7\u7528AI\u6280\u8853\u9a45\u52d5\u81ea\u7814\u4ea4\u6613\u7cfb\u7d71\u8fed\u4ee3\u5347\u7d1a\uff0c\u6b63\u5f0f\u63a8\u51fa\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\uff0c\u6df1\u5ea6\u570d\u7e5eAI\u79d1\u6280\u8ce6\u80fd\u6838\u5fc3\u696d\u52d9\u7522\u54c1\u7684\u50f9\u503c\u6df1\u5316\u3002<\/p>\n<p>\u57fa\u65bc\u539f\u5148\u50b3\u7d71\u4ea4\u6613\u5747\u4ee5\u6e2f\u5143\u7d50\u7b97\uff0c\u672c\u6b21\u7345\u5b50\u96c6\u5718\u65b0\u4e0a\u7dda\u7684\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\u5c07\u652f\u6301\u5305\u62ec\u96e2\u5cb8\u4eba\u6c11\u5e63\u548c\u7f8e\u5143\u5728\u5167\u7684\u4e00\u7cfb\u5217\u8ca8\u5e63\u7684\u5b9a\u50f9\u548c\u7d50\u7b97\u3002\u8a72\u7cfb\u7d71\u5c07\u5be6\u6642\u8abf\u6574\u4ee5\u9069\u61c9\u4e0d\u540c\u7684\u8ca8\u5e63\u8cec\u6236\uff0c\u70ba\u5168\u7403\u5404\u985e\u7528\u6236\u63d0\u4f9b\u66f4\u5c08\u696d\u4e14\u66f4\u667a\u6167\u5316\u7684\u6295\u8cc7\u5de5\u5177\u548c\u4ea4\u6613\u670d\u52d9\u9ad4\u9a57\u3002<\/p>\n<p>\u6b64\u5916\uff0c\u4f5c\u70ba\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\u7684\u6838\u5fc3\u512a\u52e2\u4e4b\u4e00\u662f\u8b93\u6295\u8cc7\u8005\u4eab\u53d7\u986f\u8457\u7684\u6210\u672c\u7bc0\u7701\u548c\u66f4\u9ad8\u7684\u6548\u7387\u3002\u4f8b\u5982\uff0c\u5728\u884d\u751f\u54c1\u9818\u57df\u7684\u9999\u6e2f\u5834\u5916\uff08OTC\uff09\u80a1\u7968\u671f\u6b0a\u677f\u584a\uff0c\u5916\u8cc7\u5c0d\u4e2d\u570bA\u80a1\u7684\u6295\u8cc7\u901a\u5e38\u5bb9\u6613\u53d7\u5230\u532f\u7387\u6ce2\u52d5\u7684\u5f71\u97ff\uff0c\u532f\u7387\u6ce2\u52d5\u53ef\u80fd\u6703\u5c0d\u6de8\u56de\u5831\u7522\u751f\u91cd\u5927\u5f71\u97ff\u3002\u5728\u4f7f\u7528\u65b0\u4ea4\u6613\u670d\u52d9\u4e2d\u91c7\u7528\u96e2\u5cb8\u4eba\u6c11\u5e63\u7d50\u7b97\u53ef\u4ee5\u7de9\u89e3\u8ca8\u5e63\u6ce2\u52d5\uff0c\u80fd\u5920\u6975\u5927\u5730\u63d0\u5347\u5ba2\u6236\u8ca1\u52d9\u7b56\u7565\u7684\u6d41\u52d5\u6027\u548c\u9748\u6d3b\u6027\u3002<\/p>\n<p>\u7345\u5b50\u96c6\u5718\u63a7\u80a1\u9996\u5e2d\u57f7\u884c\u5b98\u6c6a\u6625\u5be7(Wilson)\u5148\u751f\u8868\u793a\uff1a\u300c\u91d1\u878d\u3001\u79d1\u6280\u8207\u6578\u5b57\u5316\u662f\u7345\u5b50\u96c6\u5718\u5728\u91d1\u878d\u79d1\u6280\u9818\u57df\u8eac\u8eab\u524d\u884c\u7684\u4e09\u5927\u57fa\u77f3\u3002\u6211\u5011\u8a8d\u70ba\uff0c\u5728AI\u6d6a\u6f6e\u6301\u7e8c\u5e2d\u5377\u5168\u7403\u7684\u80cc\u666f\u4e0b\uff0c\u7a4d\u6975\u628a\u63e1AI\u5e36\u4f86\u7684\u884c\u696d\u6a5f\u6703\uff0c\u70ba\u516c\u53f8\u5404\u9805\u6838\u5fc3\u696d\u52d9\u7522\u54c1\u8207\u670d\u52d9\u6ce8\u5165AI\u52d5\u80fd\u3002\u8af8\u5982\u6b64\u756a\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\u7684\u4e0a\u7dda\uff0c\u5c07\u5927\u5e45\u63d0\u5347\u76f8\u61c9\u7522\u54c1\u7684\u5dee\u7570\u5316\u7af6\u722d\u529b\u8207\u5e36\u4f86\u66f4\u591a\u5e02\u5834\u589e\u91cf\u76c8\u5229\u9ede\u3002\u540c\u6642\uff0c\u53d7\u76ca\u65bc\u591a\u5143\u5316\u767c\u5c55\u6230\u7565\u5e03\u5c40\uff0c\u7345\u5b50\u96c6\u5718\u5c07\u50be\u529b\u6253\u9020\u7a69\u5065\u4e14\u5bcc\u6709\u60f3\u8c61\u529b\u7684\u696d\u52d9\u9ad4\u7cfb\u5efa\u8a2d\uff0c\u70ba\u5ba2\u6236\u63d0\u4f9b\u66f4\u512a\u8cea\u7684\u7522\u54c1\u9ad4\u9a57\u548c\u670d\u52d9\uff0c\u70ba\u80a1\u6771\u5275\u9020\u6709\u610f\u7fa9\u7684\u50f9\u503c\u589e\u9577\u3002\u300d<\/p>\n<p>\u95dc\u65bc\u7345\u5b50\u96c6\u5718\u63a7\u80a1<\/p>\n<p>\u7345\u5b50\u96c6\u5718\u63a7\u80a1\u6709\u9650\u516c\u53f8(\u7d0d\u65af\u9054\u514b\u80a1\u7968\u4ee3\u78bc\uff1aLGHL)\u904b\u71df\u8457\u4e00\u500b\u4e00\u7ad9\u5f0f\u5168\u65b9\u4f4d\u7684\u4ea4\u6613\u5e73\u53f0\uff0c\u70ba\u6295\u8cc7\u8005\u63d0\u4f9b\u5ee3\u6cdb\u7684\u7522\u54c1\u548c\u670d\u52d9\uff0c\u5305\u62ec(i)\u7e3d\u6536\u76ca\u4e92\u63db(TRS)\u4ea4\u6613\uff0c(ii)\u5dee\u50f9\u5408\u7d04(CFD)\u4ea4\u6613\uff0c(iii)\u9999\u6e2f\u5834\u5916\u671f\u6b0a(OTC options)\u4ea4\u6613\uff0c\u4ee5\u53ca(iv)\u671f\u8ca8\u548c\u8b49\u5238\u7d93\u7d00\u3002\u6b64\u5916\uff0c\u7345\u5b50\u96c6\u5718\u64c1\u6709\u4e00\u652f\u5c08\u696d\u4e14\u7d93\u9a57\u8c50\u5bcc\u7684SPAC\u767c\u8d77\u7ba1\u7406\u5718\u968a\uff0c\u6b63\u5728\u6210\u70baSPAC\u9818\u57df\u7684\u9818\u5c0e\u8005\uff0c\u5e6b\u52a9\u5f15\u5c0e\u79c1\u71df\u516c\u53f8\u5b8c\u6210\u4e0a\u5e02\u4e4b\u65c5\uff0c\u540c\u6642\u70ba\u7345\u5b50\u96c6\u5718\u81ea\u8eab\u5275\u9020\u50f9\u503c\u3002\u66f4\u591a\u4fe1\u606f\u8acb\u8a2a\u554f <a href=\"http:\/\/ir.liongrouphl.com\/\" target=\"_blank\" rel=\"noopener\">http:\/\/ir.liongrouphl.com<\/a>\u3002<\/p>\n<p>\u524d\u77bb\u6027\u8072\u660e<\/p>\n<p>\u672c\u65b0\u805e\u7a3f\u5305\u542b1995\u5e74\u300a\u79c1\u4eba\u8b49\u5238\u8a34\u8a1f\u6539\u9769\u6cd5\u6848\u300b\u4e2d\u300c\u5b89\u5168\u6e2f\u300d\u689d\u6b3e\u542b\u7fa9\u5167\u7684\u300c\u524d\u77bb\u6027\u9673\u8ff0\u300d\u3002\u7345\u5b50\u63a7\u80a1\u7684\u5be6\u969b\u7d50\u679c\u53ef\u80fd\u8207\u4ed6\u5011\u7684\u9810\u671f\u3001\u4f30\u8a08\u548c\u9810\u6e2c\u6709\u6240\u4e0d\u540c\uff0c\u56e0\u6b64\uff0c\u60a8\u4e0d\u61c9\u5c07\u9019\u4e9b\u524d\u77bb\u6027\u9673\u8ff0\u4f5c\u70ba\u5c0d\u672a\u4f86\u4e8b\u4ef6\u7684\u9810\u6e2c\u3002\u8af8\u5982\u300c\u671f\u671b\u300d\u3001\u300c\u4f30\u8a08\u300d\u3001\u300c\u9810\u7b97\u300d\u3001\u300c\u9810\u6e2c\u300d\u3001\u300c\u9810\u671f\u300d\u3001\u300c\u6253\u7b97\u300d\u3001\u300c\u8a08\u5283\u300d\u3001\u300c\u53ef\u80fd\u300d\u3001\u300c\u5c07\u6703\u300d\u3001\u300c\u61c9\u8a72\u300d \u3001\u300c\u76f8\u4fe1\u300d\u3001\u300c\u6f5b\u529b\u300d\u548c\u300c\u7e7c\u7e8c\u300d\u7b49\u8a5e\u8a9e\u4ee5\u53ca\u985e\u4f3c\u7684\u8868\u8ff0\u65e8\u5728\u8b58\u5225\u6b64\u985e\u524d\u77bb\u6027\u9673\u8ff0\u3002\u9019\u4e9b\u524d\u77bb\u6027\u9673\u8ff0\u5305\u62ec\uff0c\u4f46\u4e0d\u9650\u65bc\uff1a\u6211\u5011\u7684\u76ee\u6a19\u548c\u8a08\u5283\uff1b\u6211\u5011\u64f4\u5f35\u696d\u52d9\u548c\u670d\u52d9\u7684\u80fd\u529b\uff1b\u6211\u5011\u7684\u7d93\u71df\u548c\u8ca1\u52d9\u72c0\u6cc1\uff1b\u5c0d\u672a\u4f86\u71df\u6536\u8207\u652f\u51fa\u8b8a\u5316\u7684\u9810\u8a08\uff1bCOVID-19\u5c0d\u6211\u5011\u696d\u52d9\u7684\u5f71\u97ff\uff1b\u884c\u696d\u5167\u7684\u7af6\u722d\uff1b\u653f\u5e9c\u5c0d\u6211\u5011\u7d93\u71df\u884c\u696d\u7684\u653f\u7b56\u8207\u7ba1\u7406\uff1b\u5168\u7403\u8207\u4e2d\u570b\u7684\u7d93\u6fdf\u548c\u5e02\u5834\u74b0\u5883\uff1b\u4ee5\u53ca\u4efb\u4f55\u57fa\u65bc\u5c0d\u524d\u9762\u56e0\u7d20\u7684\u5047\u8a2d\u3002\u7345\u5b50\u63a7\u80a1\u8b66\u544a\u4e0a\u8ff0\u56e0\u7d20\u4e0d\u5177\u6392\u4ed6\u6027\u3002\u7345\u5b50\u63a7\u80a1\u544a\u8aa1\u8b80\u8005\u4e0d\u8981\u904e\u5206\u4f9d\u8cf4\u4efb\u4f55\u524d\u77bb\u6027\u9673\u8ff0\uff0c\u9019\u4e9b\u9673\u8ff0\u50c5\u5728\u767c\u5e03\u4e4b\u65e5\u751f\u6548\u3002\u7345\u5b50\u96c6\u5718\u63a7\u80a1\u4e0d\u627f\u64d4\u6216\u63a5\u53d7\u4efb\u4f55\u7fa9\u52d9\u6216\u627f\u8afe\u516c\u958b\u767c\u5e03\u5c0d\u4efb\u4f55\u524d\u77bb\u6027\u9673\u8ff0\u7684\u66f4\u65b0\u6216\u4fee\u8a02\uff0c\u4ee5\u53cd\u6620\u5176\u9810\u671f\u7684\u4efb\u4f55\u8b8a\u5316\u6216\u4efb\u4f55\u6b64\u985e\u9673\u8ff0\u6240\u4f9d\u64da\u7684\u4e8b\u4ef6\u3001\u689d\u4ef6\u6216\u60c5\u6cc1\u7684\u4efb\u4f55\u8b8a\u5316\uff0c\u4f46\u9808\u53d7\u9069\u7528\u6cd5\u5f8b\u7684\u7d04\u675f\u3002\u66f4\u591a\u4fe1\u606f\u53ef\u4ee5\u5728\u7345\u5b50\u96c6\u5718\u5411\u7f8e\u570b\u8b49\u76e3\u6703\u62ab\u9732\u6587\u4ef6\u4e2d\u7372\u53d6\uff0c\u5305\u62ec\u6211\u5011\u5411\u7f8e\u570b\u8b49\u76e3\u6703\u63d0\u4ea4\u76842022\u5e74\u5ea6\u7684\u5e74\u5831\u3002\u7345\u5b50\u96c6\u5718\u5411\u7f8e\u570b\u8b49\u76e3\u6703\u516c\u958b\u7533\u5831\u7684\u6587\u4ef6\u53ef\u4ee5\u5728\u7f8e\u570b\u8b49\u76e3\u6703\u7db2\u7ad9<a href=\"http:\/\/www.sec.gov\/\" target=\"_blank\" rel=\"noopener\">www.sec.gov<\/a>\u7372\u53d6\u3002<\/p>\n<p>\u00a0<\/p>","protected":false},"excerpt":{"rendered":"<p>\u9999\u6e2f2024\u5e744\u670822\u65e5 \/\u7f8e\u901a\u793e\/ &#8212; \u7345\u5b50\u96c6\u5718\u63a7\u80a1\u6709\u9650\u516c\u53f8(Lion Group Holding Ltd.)(&#8220;\u7345\u5b50\u96c6\u5718&#8221;\u6216&#8221;\u8a72\u96c6\u5718&#8221;)(\u7d0d\u65af\u9054\u514b\u80a1\u7968\u4ee3\u78bc\uff1aLGHL)\uff0c\u662f\u4e00\u5bb6\u70ba\u6295\u8cc7\u8005\u63d0\u4f9b\u5ee3\u6cdb\u7522\u54c1\u548c\u670d\u52d9\u7684\u4e00\u7ad9\u5f0f\u4ea4\u6613\u5e73\u53f0\u904b\u71df\u5546\uff0c\u4ee5\u53ca\u5c08\u6ce8\u65bc\u91d1\u878d\u79d1\u6280\u9818\u57df\u7684\u5275\u65b0\u7522\u54c1\u958b\u767c\u8005\u3002\u8a72\u96c6\u5718\u4eca\u65e5\u5ba3\u5e03\u91c7\u7528AI\u6280\u8853\u9a45\u52d5\u81ea\u7814\u4ea4\u6613\u7cfb\u7d71\u8fed\u4ee3\u5347\u7d1a\uff0c\u6b63\u5f0f\u63a8\u51fa\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\uff0c\u6df1\u5ea6\u570d\u7e5eAI\u79d1\u6280\u8ce6\u80fd\u6838\u5fc3\u696d\u52d9\u7522\u54c1\u7684\u50f9\u503c\u6df1\u5316\u3002 \u57fa\u65bc\u539f\u5148\u50b3\u7d71\u4ea4\u6613\u5747\u4ee5\u6e2f\u5143\u7d50\u7b97\uff0c\u672c\u6b21\u7345\u5b50\u96c6\u5718\u65b0\u4e0a &#8230; <\/p>\n<p class=\"read-more-container\"><a title=\"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9\" class=\"read-more button\" href=\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#more-18555\" aria-label=\"\u66f4\u591a \u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9\">\u4e86\u89e3\u8a73\u60c5<\/a><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_generate-full-width-content":"","spay_email":"","footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9 - \u9999\u6e2f\u7279\u8a31\u7d93\u71df<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\" \/>\n<meta property=\"og:locale\" content=\"zh_CN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9 - \u9999\u6e2f\u7279\u8a31\u7d93\u71df\" \/>\n<meta property=\"og:description\" content=\"\u9999\u6e2f2024\u5e744\u670822\u65e5 \/\u7f8e\u901a\u793e\/ &#8212; \u7345\u5b50\u96c6\u5718\u63a7\u80a1\u6709\u9650\u516c\u53f8(Lion Group Holding Ltd.)(&#8220;\u7345\u5b50\u96c6\u5718&#8221;\u6216&#8221;\u8a72\u96c6\u5718&#8221;)(\u7d0d\u65af\u9054\u514b\u80a1\u7968\u4ee3\u78bc\uff1aLGHL)\uff0c\u662f\u4e00\u5bb6\u70ba\u6295\u8cc7\u8005\u63d0\u4f9b\u5ee3\u6cdb\u7522\u54c1\u548c\u670d\u52d9\u7684\u4e00\u7ad9\u5f0f\u4ea4\u6613\u5e73\u53f0\u904b\u71df\u5546\uff0c\u4ee5\u53ca\u5c08\u6ce8\u65bc\u91d1\u878d\u79d1\u6280\u9818\u57df\u7684\u5275\u65b0\u7522\u54c1\u958b\u767c\u8005\u3002\u8a72\u96c6\u5718\u4eca\u65e5\u5ba3\u5e03\u91c7\u7528AI\u6280\u8853\u9a45\u52d5\u81ea\u7814\u4ea4\u6613\u7cfb\u7d71\u8fed\u4ee3\u5347\u7d1a\uff0c\u6b63\u5f0f\u63a8\u51fa\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\uff0c\u6df1\u5ea6\u570d\u7e5eAI\u79d1\u6280\u8ce6\u80fd\u6838\u5fc3\u696d\u52d9\u7522\u54c1\u7684\u50f9\u503c\u6df1\u5316\u3002 \u57fa\u65bc\u539f\u5148\u50b3\u7d71\u4ea4\u6613\u5747\u4ee5\u6e2f\u5143\u7d50\u7b97\uff0c\u672c\u6b21\u7345\u5b50\u96c6\u5718\u65b0\u4e0a ... \u4e86\u89e3\u8a73\u60c5\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\" \/>\n<meta property=\"og:site_name\" content=\"\u9999\u6e2f\u7279\u8a31\u7d93\u71df\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-22T04:30:00+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9\",\"datePublished\":\"2024-04-22T04:30:00+00:00\",\"dateModified\":\"2024-04-22T04:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\"},\"wordCount\":35,\"publisher\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#organization\"},\"articleSection\":[\"\u672a\u5206\u985e\"],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\",\"url\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\",\"name\":\"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9 - \u9999\u6e2f\u7279\u8a31\u7d93\u71df\",\"isPartOf\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#website\"},\"datePublished\":\"2024-04-22T04:30:00+00:00\",\"dateModified\":\"2024-04-22T04:30:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#breadcrumb\"},\"inLanguage\":\"zh-Hans\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9801\",\"item\":\"https:\/\/www.franchise.com.hk\/zh-hans\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#website\",\"url\":\"https:\/\/www.franchise.com.hk\/zh-hans\",\"name\":\"\u9999\u6e2f\u7279\u8a31\u7d93\u71df\",\"description\":\"\u9999\u6e2f\u7279\u8a31\u7d93\u71df | Franchise HK\",\"publisher\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.franchise.com.hk\/zh-hans?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"zh-Hans\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#organization\",\"name\":\"\u9999\u6e2f\u7279\u8a31\u7d93\u71df\",\"url\":\"https:\/\/www.franchise.com.hk\/zh-hans\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"zh-Hans\",\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#\/schema\/logo\/image\/\",\"url\":\"https:\/\/i0.wp.com\/www.franchise.com.hk\/wp-content\/uploads\/2022\/05\/cropped-cropped-franchise-logo-02-e1652686851566-2.png?fit=350%2C76&ssl=1\",\"contentUrl\":\"https:\/\/i0.wp.com\/www.franchise.com.hk\/wp-content\/uploads\/2022\/05\/cropped-cropped-franchise-logo-02-e1652686851566-2.png?fit=350%2C76&ssl=1\",\"width\":350,\"height\":76,\"caption\":\"\u9999\u6e2f\u7279\u8a31\u7d93\u71df\"},\"image\":{\"@id\":\"https:\/\/www.franchise.com.hk\/zh-hans#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9 - \u9999\u6e2f\u7279\u8a31\u7d93\u71df","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555","og_locale":"zh_CN","og_type":"article","og_title":"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9 - \u9999\u6e2f\u7279\u8a31\u7d93\u71df","og_description":"\u9999\u6e2f2024\u5e744\u670822\u65e5 \/\u7f8e\u901a\u793e\/ &#8212; \u7345\u5b50\u96c6\u5718\u63a7\u80a1\u6709\u9650\u516c\u53f8(Lion Group Holding Ltd.)(&#8220;\u7345\u5b50\u96c6\u5718&#8221;\u6216&#8221;\u8a72\u96c6\u5718&#8221;)(\u7d0d\u65af\u9054\u514b\u80a1\u7968\u4ee3\u78bc\uff1aLGHL)\uff0c\u662f\u4e00\u5bb6\u70ba\u6295\u8cc7\u8005\u63d0\u4f9b\u5ee3\u6cdb\u7522\u54c1\u548c\u670d\u52d9\u7684\u4e00\u7ad9\u5f0f\u4ea4\u6613\u5e73\u53f0\u904b\u71df\u5546\uff0c\u4ee5\u53ca\u5c08\u6ce8\u65bc\u91d1\u878d\u79d1\u6280\u9818\u57df\u7684\u5275\u65b0\u7522\u54c1\u958b\u767c\u8005\u3002\u8a72\u96c6\u5718\u4eca\u65e5\u5ba3\u5e03\u91c7\u7528AI\u6280\u8853\u9a45\u52d5\u81ea\u7814\u4ea4\u6613\u7cfb\u7d71\u8fed\u4ee3\u5347\u7d1a\uff0c\u6b63\u5f0f\u63a8\u51fa\u591a\u5e63\u7a2e\u4ea4\u6613\u8cec\u6236\u670d\u52d9\uff0c\u6df1\u5ea6\u570d\u7e5eAI\u79d1\u6280\u8ce6\u80fd\u6838\u5fc3\u696d\u52d9\u7522\u54c1\u7684\u50f9\u503c\u6df1\u5316\u3002 \u57fa\u65bc\u539f\u5148\u50b3\u7d71\u4ea4\u6613\u5747\u4ee5\u6e2f\u5143\u7d50\u7b97\uff0c\u672c\u6b21\u7345\u5b50\u96c6\u5718\u65b0\u4e0a ... \u4e86\u89e3\u8a73\u60c5","og_url":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555","og_site_name":"\u9999\u6e2f\u7279\u8a31\u7d93\u71df","article_published_time":"2024-04-22T04:30:00+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#article","isPartOf":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555"},"author":{"name":"","@id":""},"headline":"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9","datePublished":"2024-04-22T04:30:00+00:00","dateModified":"2024-04-22T04:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555"},"wordCount":35,"publisher":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans#organization"},"articleSection":["\u672a\u5206\u985e"],"inLanguage":"zh-Hans"},{"@type":"WebPage","@id":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555","url":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555","name":"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9 - \u9999\u6e2f\u7279\u8a31\u7d93\u71df","isPartOf":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans#website"},"datePublished":"2024-04-22T04:30:00+00:00","dateModified":"2024-04-22T04:30:00+00:00","breadcrumb":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#breadcrumb"},"inLanguage":"zh-Hans","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.franchise.com.hk\/zh-hans\/%e7%8d%85%e5%ad%90%e9%9b%86%e5%9c%98%e6%8e%a7%e8%82%a1lghl-us%e5%ae%98%e5%ae%a3%e4%b8%8a%e7%b7%9a%e5%a4%9a%e5%b9%a3%e7%a8%ae%e8%b3%ac%e6%88%b6%e6%9c%8d%e5%8b%99\/18555#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9801","item":"https:\/\/www.franchise.com.hk\/zh-hans"},{"@type":"ListItem","position":2,"name":"\u7345\u5b50\u96c6\u5718\u63a7\u80a1(LGHL.US)\u5b98\u5ba3\u4e0a\u7dda\u591a\u5e63\u7a2e\u8cec\u6236\u670d\u52d9"}]},{"@type":"WebSite","@id":"https:\/\/www.franchise.com.hk\/zh-hans#website","url":"https:\/\/www.franchise.com.hk\/zh-hans","name":"\u9999\u6e2f\u7279\u8a31\u7d93\u71df","description":"\u9999\u6e2f\u7279\u8a31\u7d93\u71df | Franchise HK","publisher":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.franchise.com.hk\/zh-hans?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"zh-Hans"},{"@type":"Organization","@id":"https:\/\/www.franchise.com.hk\/zh-hans#organization","name":"\u9999\u6e2f\u7279\u8a31\u7d93\u71df","url":"https:\/\/www.franchise.com.hk\/zh-hans","logo":{"@type":"ImageObject","inLanguage":"zh-Hans","@id":"https:\/\/www.franchise.com.hk\/zh-hans#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/www.franchise.com.hk\/wp-content\/uploads\/2022\/05\/cropped-cropped-franchise-logo-02-e1652686851566-2.png?fit=350%2C76&ssl=1","contentUrl":"https:\/\/i0.wp.com\/www.franchise.com.hk\/wp-content\/uploads\/2022\/05\/cropped-cropped-franchise-logo-02-e1652686851566-2.png?fit=350%2C76&ssl=1","width":350,"height":76,"caption":"\u9999\u6e2f\u7279\u8a31\u7d93\u71df"},"image":{"@id":"https:\/\/www.franchise.com.hk\/zh-hans#\/schema\/logo\/image\/"}}]}},"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/posts\/18555"}],"collection":[{"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/comments?post=18555"}],"version-history":[{"count":0,"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/posts\/18555\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/media?parent=18555"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/categories?post=18555"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.franchise.com.hk\/zh-hans\/wp-json\/wp\/v2\/tags?post=18555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}